{"id":13071,"date":"2022-12-21T10:56:10","date_gmt":"2022-12-21T03:56:10","guid":{"rendered":"https:\/\/tephuket.com\/?p=13071"},"modified":"2022-12-21T10:56:10","modified_gmt":"2022-12-21T03:56:10","slug":"te-staff-seminar","status":"publish","type":"post","link":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/","title":{"rendered":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13071\" class=\"elementor elementor-13071\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c528c7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c528c7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49805d1c\" data-id=\"49805d1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-708a59c7 elementor-widget elementor-widget-text-editor\" data-id=\"708a59c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p class=\"wp-block-paragraph\">\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e2a\u0e32\u0e22\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566\u00a0 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c AERIC \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2565 \u0e40\u0e27\u0e25\u0e32 09.30 &#8211; 16.30 \u0e19. \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e2a\u0e38\u0e18\u0e35\u0e23\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-438925f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"438925f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0b203d7\" data-id=\"0b203d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7ede32 elementor-widget elementor-widget-gallery\" data-id=\"f7ede32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e2a\u0e32\u0e22\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566\u00a0 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c AERIC \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2565 \u0e40\u0e27\u0e25\u0e32 09.30 &#8211; 16.30 \u0e19. \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e2a\u0e38\u0e18\u0e35\u0e23\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23<\/p>\n","protected":false},"author":1,"featured_media":13267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3],"tags":[],"class_list":["post-13071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-te-news","category-3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 - \u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 - \u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\" \/>\n<meta property=\"og:description\" content=\"\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e2a\u0e32\u0e22\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566\u00a0 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c AERIC \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2565 \u0e40\u0e27\u0e25\u0e32 09.30 &#8211; 16.30 \u0e19. \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e2a\u0e38\u0e18\u0e35\u0e23\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\" \/>\n<meta property=\"og:url\" content=\"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-21T03:56:10+00:00\" \/>\n<meta name=\"author\" content=\"yannawat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"yannawat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/\"},\"author\":{\"name\":\"yannawat\",\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/#\\\/schema\\\/person\\\/3e5bd46245b9ce57c2ce0507f80c6d10\"},\"headline\":\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\",\"datePublished\":\"2022-12-21T03:56:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/\"},\"wordCount\":2,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"TE-NEWS\",\"\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e20\u0e32\u0e1e\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/\",\"url\":\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/\",\"name\":\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 - \u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2022-12-21T03:56:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/2022\\\/12\\\/21\\\/te-staff-seminar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/te.psu.ac.th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/#website\",\"url\":\"https:\\\/\\\/te.psu.ac.th\\\/\",\"name\":\"\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/te.psu.ac.th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/#organization\",\"name\":\"\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\",\"url\":\"https:\\\/\\\/te.psu.ac.th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/te.psu.ac.th\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo_Subbrand_Faculty-of-Technology_and_Environment_Full_EN.png\",\"contentUrl\":\"https:\\\/\\\/te.psu.ac.th\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo_Subbrand_Faculty-of-Technology_and_Environment_Full_EN.png\",\"width\":3936,\"height\":800,\"caption\":\"\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\"},\"image\":{\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/te.psu.ac.th\\\/#\\\/schema\\\/person\\\/3e5bd46245b9ce57c2ce0507f80c6d10\",\"name\":\"yannawat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f050e408a4f4d78a8eb7e63c2b06b4880ceee073484678fa404cd0f5c036e862?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f050e408a4f4d78a8eb7e63c2b06b4880ceee073484678fa404cd0f5c036e862?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f050e408a4f4d78a8eb7e63c2b06b4880ceee073484678fa404cd0f5c036e862?s=96&d=mm&r=g\",\"caption\":\"yannawat\"},\"sameAs\":[\"https:\\\/\\\/te.psu.ac.th\"],\"url\":\"https:\\\/\\\/te.psu.ac.th\\\/index.php\\\/author\\\/yannawat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 - \u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/","og_locale":"en_US","og_type":"article","og_title":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 - \u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21","og_description":"\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e2a\u0e32\u0e22\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566\u00a0 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c AERIC \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2565 \u0e40\u0e27\u0e25\u0e32 09.30 &#8211; 16.30 \u0e19. \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e2a\u0e38\u0e18\u0e35\u0e23\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23","og_url":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/","og_site_name":"\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21","article_published_time":"2022-12-21T03:56:10+00:00","author":"yannawat","twitter_card":"summary_large_image","twitter_misc":{"Written by":"yannawat","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/#article","isPartOf":{"@id":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/"},"author":{"name":"yannawat","@id":"https:\/\/te.psu.ac.th\/#\/schema\/person\/3e5bd46245b9ce57c2ce0507f80c6d10"},"headline":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19","datePublished":"2022-12-21T03:56:10+00:00","mainEntityOfPage":{"@id":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/"},"wordCount":2,"commentCount":0,"publisher":{"@id":"https:\/\/te.psu.ac.th\/#organization"},"image":{"@id":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/#primaryimage"},"thumbnailUrl":"","articleSection":["TE-NEWS","\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e20\u0e32\u0e1e\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/","url":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/","name":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 - \u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21","isPartOf":{"@id":"https:\/\/te.psu.ac.th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/#primaryimage"},"image":{"@id":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/#primaryimage"},"thumbnailUrl":"","datePublished":"2022-12-21T03:56:10+00:00","breadcrumb":{"@id":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/te.psu.ac.th\/index.php\/2022\/12\/21\/te-staff-seminar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/te.psu.ac.th\/"},{"@type":"ListItem","position":2,"name":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19"}]},{"@type":"WebSite","@id":"https:\/\/te.psu.ac.th\/#website","url":"https:\/\/te.psu.ac.th\/","name":"\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21","description":"","publisher":{"@id":"https:\/\/te.psu.ac.th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/te.psu.ac.th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/te.psu.ac.th\/#organization","name":"\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21","url":"https:\/\/te.psu.ac.th\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/te.psu.ac.th\/#\/schema\/logo\/image\/","url":"https:\/\/te.psu.ac.th\/wp-content\/uploads\/2024\/04\/Logo_Subbrand_Faculty-of-Technology_and_Environment_Full_EN.png","contentUrl":"https:\/\/te.psu.ac.th\/wp-content\/uploads\/2024\/04\/Logo_Subbrand_Faculty-of-Technology_and_Environment_Full_EN.png","width":3936,"height":800,"caption":"\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21"},"image":{"@id":"https:\/\/te.psu.ac.th\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/te.psu.ac.th\/#\/schema\/person\/3e5bd46245b9ce57c2ce0507f80c6d10","name":"yannawat","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f050e408a4f4d78a8eb7e63c2b06b4880ceee073484678fa404cd0f5c036e862?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f050e408a4f4d78a8eb7e63c2b06b4880ceee073484678fa404cd0f5c036e862?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f050e408a4f4d78a8eb7e63c2b06b4880ceee073484678fa404cd0f5c036e862?s=96&d=mm&r=g","caption":"yannawat"},"sameAs":["https:\/\/te.psu.ac.th"],"url":"https:\/\/te.psu.ac.th\/index.php\/author\/yannawat\/"}]}},"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"yannawat","author_link":"https:\/\/te.psu.ac.th\/index.php\/author\/yannawat\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/te.psu.ac.th\/index.php\/category\/te-news\/\" rel=\"category tag\">TE-NEWS<\/a> <a href=\"https:\/\/te.psu.ac.th\/index.php\/category\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%a1%e0%b8%a7%e0%b8%a5%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1\/\" rel=\"category tag\">\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e20\u0e32\u0e1e\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21<\/a>","rttpg_excerpt":"\u0e04\u0e13\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e2a\u0e32\u0e22\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566\u00a0 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c AERIC \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2565 \u0e40\u0e27\u0e25\u0e32 09.30 &#8211; 16.30 \u0e19. \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e2a\u0e38\u0e18\u0e35\u0e23\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23","_links":{"self":[{"href":"https:\/\/te.psu.ac.th\/index.php\/wp-json\/wp\/v2\/posts\/13071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/te.psu.ac.th\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/te.psu.ac.th\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/te.psu.ac.th\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/te.psu.ac.th\/index.php\/wp-json\/wp\/v2\/comments?post=13071"}],"version-history":[{"count":0,"href":"https:\/\/te.psu.ac.th\/index.php\/wp-json\/wp\/v2\/posts\/13071\/revisions"}],"wp:attachment":[{"href":"https:\/\/te.psu.ac.th\/index.php\/wp-json\/wp\/v2\/media?parent=13071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/te.psu.ac.th\/index.php\/wp-json\/wp\/v2\/categories?post=13071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/te.psu.ac.th\/index.php\/wp-json\/wp\/v2\/tags?post=13071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}